{"id":1082,"date":"2021-06-24T15:46:53","date_gmt":"2021-06-24T18:46:53","guid":{"rendered":"https:\/\/oicriativas.faac.unesp.br\/?p=1082"},"modified":"2021-06-24T15:46:54","modified_gmt":"2021-06-24T18:46:54","slug":"coletividade-ideias-que-tomam-forma","status":"publish","type":"post","link":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/","title":{"rendered":"Coletividade: ideias que tomam forma"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"><em>Hoje voc\u00ea conhecer\u00e1 a hist\u00f3ria da designer Caroline Gomes, que com a ajuda do s\u00f3cio Thomas Musmann <em>encontrou no Coletivo Boitat\u00e1<\/em> o verdadeiro poder do trabalho colaborativo.<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-neve-link-color-background-color has-neve-link-color-color is-style-wide\"\/>\n\n\n\n<p>Transformar o aprendizado de uma gradua\u00e7\u00e3o na execu\u00e7\u00e3o de uma profiss\u00e3o, aplicada no dia a dia, nem sempre \u00e9 uma tarefa simples, especialmente no come\u00e7o do trajeto. Foi isso que a Caroline Gomes descobriu l\u00e1 no in\u00edcio da \u00faltima d\u00e9cada, perto de 2010, quando viu seu primeiro <em>freela <\/em>se transformar, assim como a Hidra para a mitologia grega, em algo que crescia exponencialmente. O que come\u00e7ou com a cria\u00e7\u00e3o solo de uma logomarca para um evento cultural, acabou se tornando um projeto gr\u00e1fico e visual completo, do flyer ao outdoor, desenvolvido por dez m\u00e3os, com muita troca, colabora\u00e7\u00e3o e aprendizado. E foi assim, atrav\u00e9s da uni\u00e3o despretensiosa de amigos que decidiram se ajudar, que nasceu o que viria a ser o Coletivo Boitat\u00e1.<\/p>\n\n\n\n<p>Da elabora\u00e7\u00e3o de um Trabalho de Conclus\u00e3o de Curso realizado atrav\u00e9s da imers\u00e3o de sentidos, \u00e0 consci\u00eancia corporal trabalhada nas aulas de teatro, passando pelo desenvolvimento do pr\u00f3prio neg\u00f3cio, Caroline n\u00e3o demorou a compreender que a experimenta\u00e7\u00e3o, a coletividade e a partilha s\u00e3o os elementos que comp\u00f5em a alma da economia criativa. Foi na solu\u00e7\u00e3o de problemas e nas decis\u00f5es mais dif\u00edceis que ela descobriu a for\u00e7a que tem a colabora\u00e7\u00e3o, e que hoje, nove anos depois do surgimento da empresa, \u201c\u00e9 uma palavra que ainda faz muito sentido\u201d.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-right is-style-default\"><p>A gente percebeu que toda essa trajet\u00f3ria n\u00e3o era t\u00e3o nova assim, no sentido de que tem gente ajudando, tem uma rede. Eu sinto um acreditar ao redor e isso faz diferen\u00e7a.<\/p><cite>Caroline Gomes<\/cite><\/blockquote>\n\n\n\n<p>Assim como prega um dos principais mantras do setor criativo, Carol nunca esteve sozinha. Desde o dia um, quando o t\u00edtulo de \u201ccoletivo\u201d nem sequer passava pela cabe\u00e7a de nenhum de seus futuros colaboradores, Thomas Musmann, melhor amigo e hoje s\u00f3cio-fundador do Coletivo Boitat\u00e1, sempre esteve preparado para oferecer a ajuda necess\u00e1ria. Foi Thom que plantou, mesmo que de maneira inconsciente, a semente da partilha que se tornaria a empresa, fortalecendo a uni\u00e3o e abrindo novos caminhos para a dupla. \u201cFoi engra\u00e7ado porque a gente descobriu ali que a gente tinha muito pra aprender, sabe? Juntos ficava mais f\u00e1cil, de encarar um festival, de encarar um projeto.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/06\/Capa-Mulheres-na-Economia-Criativa.png\"><img decoding=\"async\" loading=\"lazy\" width=\"930\" height=\"620\" src=\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/06\/Capa-Mulheres-na-Economia-Criativa.png\" alt=\"\" class=\"wp-image-1087\" srcset=\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/06\/Capa-Mulheres-na-Economia-Criativa.png 930w, https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/06\/Capa-Mulheres-na-Economia-Criativa-300x200.png 300w, https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/06\/Capa-Mulheres-na-Economia-Criativa-768x512.png 768w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/><\/a><figcaption><strong>Coletividade: ideias que tomam forma<\/strong>\u00a0\u00e9 o terceiro texto da s\u00e9rie \u201c<strong>Mulheres na Economia Criativa<\/strong>\u201d, um produto OiCriativas e Lecotec.\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/05\/27\/colab-comunicacao-no-mercado-colaborativo\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/05\/27\/colab-comunicacao-no-mercado-colaborativo\/\">Clique aqui para conferir o segundo texto da s\u00e9rie<\/a>\u00a0\u2013 Imagem: Divulga\u00e7\u00e3o\/OiCriativas<\/figcaption><\/figure>\n\n\n\n<p>Filha de empreendedores, Carol j\u00e1 tinha a independ\u00eancia, a inova\u00e7\u00e3o e a criatividade dentro de si, e a transi\u00e7\u00e3o da vida sob regime CLT para o setor da economia criativa veio como uma busca por reconex\u00e3o. Para a designer, empreender \u00e9 liberdade. \u00c9 sobre respeitar o pr\u00f3prio tempo e poder aliar o trabalho com qualidade de vida e bem estar: \u201c\u00e9 poder estar na rua \u00e0s quatro da tarde\u201d. No entanto, essa liberdade n\u00e3o pode ser confundida com falta de m\u00e9todo ou concentra\u00e7\u00e3o excessiva do trabalho, e entender isso foi essencial para a trajet\u00f3ria de Carol e Thomas. Na empresa, designers trabalham ao lado de profissionais das \u00e1reas de marketing e contabilidade, tornando a exist\u00eancia do Coletivo Boitat\u00e1 ainda mais s\u00f3lida e resistente.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-right\"><p>A gente tem um sal\u00e1rio real desde o ano passado, e por real eu digo fixo, porque antes disso a gente n\u00e3o tinha estabilidade. Foram muitos anos de \u201cEsse m\u00eas n\u00e3o tem dinheiro\u201d. Ao longo dos \u00faltimos anos a gente investiu muito em \u00e1reas que n\u00e3o s\u00e3o da nossa forma\u00e7\u00e3o. A gente precisa de ajuda de quem entende de marketing, a gente precisa de ajuda de quem entende da estrutura financeira da empresa, e essas colabora\u00e7\u00f5es ajudaram muito a fortalecer a nossa base.<\/p><cite>Caroline Gomes<\/cite><\/blockquote>\n\n\n\n<p>Para Caroline, a criatividade \u00e9 a capacidade de gerar solu\u00e7\u00f5es, e \u00e9 a\u00ed que se encontra o diferencial da empresa: \u201cA gente n\u00e3o entrega performance, venda, mas o nosso produto \u00e9 o design. O que a gente pensa \u00e9 no design, na cria\u00e7\u00e3o, na concep\u00e7\u00e3o daquilo. \u00c9 isso que a gente gosta de fazer, de resolver o problema do cliente\u201d. E \u00e9 justamente na busca pelo contato pessoal e acolhedor que se fundamenta a atua\u00e7\u00e3o do coletivo. Para eles, a colabora\u00e7\u00e3o vai muito al\u00e9m de um t\u00edtulo, \u00e9 um modo de se relacionar com os clientes, uma ferramenta de trabalho, e reconhecer a sua ess\u00eancia n\u00e3o diminui a jornada, mas aponta para a dire\u00e7\u00e3o correta e ilumina o caminho a ser trilhado.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-right\"><p>Quando voc\u00ea percebe que existe uma diferen\u00e7a oce\u00e2nica entre ser <em>freelancer <\/em>e ser empreendedor, \u00e9 assustador. Hoje a gente percebe o quanto a gente cresceu desde o momento em que a gente viu que precisava de ajuda. A caminhada \u00e9 longa mas a gente est\u00e1 na estrada, e agora eu sei o que eu estou fazendo.<\/p><cite>Caroline Gomes<\/cite><\/blockquote>\n\n\n\n<p>A experi\u00eancia da Carol com o Coletivo Boitat\u00e1 ilustra de forma clara como se d\u00e1 o desenvolvimento de uma iniciativa na economia criativa. Cada empreendedor tem seu rumo, seu objetivo e seus obst\u00e1culos a superar, e cada neg\u00f3cio tem \u00e0 sua frente uma estrada a percorrer, mas o processo se torna mais leve para aqueles que enxergam na criatividade e na uni\u00e3o, os motores para o desenvolvimento profissional.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-neve-link-color-background-color has-neve-link-color-color is-style-wide\"\/>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\">Voc\u00ea pode entrar em contato com o <strong>Coletivo Boitat\u00e1<\/strong> atrav\u00e9s da aba &#8220;Contato&#8221;, dispon\u00edvel no <a href=\"https:\/\/coletivoboitata.com.br\/contato\" target=\"_blank\" rel=\"noreferrer noopener\">site<\/a> da empresa, ou ainda enviando diretamente um <a rel=\"noreferrer noopener\" href=\"mailto:contato@coletivoboitata.com.br\" target=\"_blank\">e-mail<\/a> para o Coletivo!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-neve-link-color-background-color has-neve-link-color-color\"\/>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\"><strong>Siga o Coletivo Boitat\u00e1 nas redes sociais!<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-social-links aligncenter is-style-logos-only is-layout-flex\"><li class=\"wp-social-link wp-social-link-facebook wp-block-social-link\"><a rel=\" noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/coletivoboitata\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Facebook<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-instagram wp-block-social-link\"><a rel=\" noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/coletivoboitata\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-behance wp-block-social-link\"><a rel=\" noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.behance.net\/coletivoboitata\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M7.799,5.698c0.589,0,1.12,0.051,1.606,0.156c0.482,0.102,0.894,0.273,1.241,0.507c0.344,0.235,0.612,0.546,0.804,0.938 c0.188,0.387,0.281,0.871,0.281,1.443c0,0.619-0.141,1.137-0.421,1.551c-0.284,0.413-0.7,0.751-1.255,1.014 c0.756,0.218,1.317,0.601,1.689,1.146c0.374,0.549,0.557,1.205,0.557,1.975c0,0.623-0.12,1.161-0.359,1.612 c-0.241,0.457-0.569,0.828-0.973,1.114c-0.408,0.288-0.876,0.5-1.399,0.637C9.052,17.931,8.514,18,7.963,18H2V5.698H7.799 M7.449,10.668c0.481,0,0.878-0.114,1.192-0.345c0.311-0.228,0.463-0.603,0.463-1.119c0-0.286-0.051-0.523-0.152-0.707 C8.848,8.315,8.711,8.171,8.536,8.07C8.362,7.966,8.166,7.894,7.94,7.854c-0.224-0.044-0.457-0.06-0.697-0.06H4.709v2.874H7.449z M7.6,15.905c0.267,0,0.521-0.024,0.759-0.077c0.243-0.053,0.457-0.137,0.637-0.261c0.182-0.12,0.332-0.283,0.441-0.491 C9.547,14.87,9.6,14.602,9.6,14.278c0-0.633-0.18-1.084-0.533-1.357c-0.356-0.27-0.83-0.404-1.413-0.404H4.709v3.388L7.6,15.905z M16.162,15.864c0.367,0.358,0.897,0.538,1.583,0.538c0.493,0,0.92-0.125,1.277-0.374c0.354-0.248,0.571-0.514,0.654-0.79h2.155 c-0.347,1.072-0.872,1.838-1.589,2.299C19.534,18,18.67,18.23,17.662,18.23c-0.701,0-1.332-0.113-1.899-0.337 c-0.567-0.227-1.041-0.544-1.439-0.958c-0.389-0.415-0.689-0.907-0.904-1.484c-0.213-0.574-0.32-1.21-0.32-1.899 c0-0.666,0.11-1.288,0.329-1.863c0.222-0.577,0.529-1.075,0.933-1.492c0.406-0.42,0.885-0.751,1.444-0.994 c0.558-0.241,1.175-0.363,1.857-0.363c0.754,0,1.414,0.145,1.98,0.44c0.563,0.291,1.026,0.686,1.389,1.181 c0.363,0.493,0.622,1.057,0.783,1.69c0.16,0.632,0.217,1.292,0.171,1.983h-6.428C15.557,14.84,15.795,15.506,16.162,15.864 M18.973,11.184c-0.291-0.321-0.783-0.496-1.384-0.496c-0.39,0-0.714,0.066-0.973,0.2c-0.254,0.132-0.461,0.297-0.621,0.491 c-0.157,0.197-0.265,0.405-0.328,0.628c-0.063,0.217-0.101,0.413-0.111,0.587h3.98C19.478,11.969,19.265,11.509,18.973,11.184z M15.057,7.738h4.985V6.524h-4.985L15.057,7.738z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Behance<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-youtube wp-block-social-link\"><a rel=\" noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/channel\/UCY955yf9sGoJO1Dmn4R48BQ\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M21.8,8.001c0,0-0.195-1.378-0.795-1.985c-0.76-0.797-1.613-0.801-2.004-0.847c-2.799-0.202-6.997-0.202-6.997-0.202 h-0.009c0,0-4.198,0-6.997,0.202C4.608,5.216,3.756,5.22,2.995,6.016C2.395,6.623,2.2,8.001,2.2,8.001S2,9.62,2,11.238v1.517 c0,1.618,0.2,3.237,0.2,3.237s0.195,1.378,0.795,1.985c0.761,0.797,1.76,0.771,2.205,0.855c1.6,0.153,6.8,0.201,6.8,0.201 s4.203-0.006,7.001-0.209c0.391-0.047,1.243-0.051,2.004-0.847c0.6-0.607,0.795-1.985,0.795-1.985s0.2-1.618,0.2-3.237v-1.517 C22,9.62,21.8,8.001,21.8,8.001z M9.935,14.594l-0.001-5.62l5.404,2.82L9.935,14.594z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">YouTube<\/span><\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Hoje voc\u00ea conhecer\u00e1 a hist\u00f3ria da designer Caroline Gomes, que com a ajuda do s\u00f3cio Thomas Musmann encontrou no Coletivo Boitat\u00e1 o verdadeiro poder do trabalho colaborativo.<\/p>\n","protected":false},"author":1,"featured_media":1084,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"on","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":""},"categories":[174],"tags":[150,176,29],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coletividade: ideias que tomam forma - Oi Criativas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coletividade: ideias que tomam forma - Oi Criativas\" \/>\n<meta name=\"twitter:description\" content=\"Hoje voc\u00ea conhecer\u00e1 a hist\u00f3ria da designer Caroline Gomes, que com a ajuda do s\u00f3cio Thomas Musmann encontrou no Coletivo Boitat\u00e1 o verdadeiro poder do trabalho colaborativo.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/06\/Logo-e1624559527361.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lecotec\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/\"},\"author\":{\"name\":\"lecotec\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/8f56b3dc3c300fd061a7ee990c5a43cc\"},\"headline\":\"Coletividade: ideias que tomam forma\",\"datePublished\":\"2021-06-24T18:46:53+00:00\",\"dateModified\":\"2021-06-24T18:46:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/\"},\"wordCount\":973,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#organization\"},\"keywords\":[\"Bauru\",\"Design\",\"Economia Criativa\"],\"articleSection\":[\"Mulheres na Economia Criativa\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/\",\"name\":\"Coletividade: ideias que tomam forma - Oi Criativas\",\"isPartOf\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#website\"},\"datePublished\":\"2021-06-24T18:46:53+00:00\",\"dateModified\":\"2021-06-24T18:46:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/oicriativas.faac.unesp.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coletividade: ideias que tomam forma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#website\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/\",\"name\":\"Oi Criativas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oicriativas.faac.unesp.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#organization\",\"name\":\"Oi Criativas\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png\",\"contentUrl\":\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png\",\"width\":300,\"height\":118,\"caption\":\"Oi Criativas\"},\"image\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/8f56b3dc3c300fd061a7ee990c5a43cc\",\"name\":\"lecotec\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d04c8a97a87b9a1cb7c7db69dacde035?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d04c8a97a87b9a1cb7c7db69dacde035?s=96&d=mm&r=g\",\"caption\":\"lecotec\"},\"url\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/author\/lecotec\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coletividade: ideias que tomam forma - Oi Criativas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/","twitter_card":"summary_large_image","twitter_title":"Coletividade: ideias que tomam forma - Oi Criativas","twitter_description":"Hoje voc\u00ea conhecer\u00e1 a hist\u00f3ria da designer Caroline Gomes, que com a ajuda do s\u00f3cio Thomas Musmann encontrou no Coletivo Boitat\u00e1 o verdadeiro poder do trabalho colaborativo.","twitter_image":"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/06\/Logo-e1624559527361.png","twitter_misc":{"Escrito por":"lecotec","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/#article","isPartOf":{"@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/"},"author":{"name":"lecotec","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/8f56b3dc3c300fd061a7ee990c5a43cc"},"headline":"Coletividade: ideias que tomam forma","datePublished":"2021-06-24T18:46:53+00:00","dateModified":"2021-06-24T18:46:54+00:00","mainEntityOfPage":{"@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/"},"wordCount":973,"commentCount":1,"publisher":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#organization"},"keywords":["Bauru","Design","Economia Criativa"],"articleSection":["Mulheres na Economia Criativa"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/","url":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/","name":"Coletividade: ideias que tomam forma - Oi Criativas","isPartOf":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#website"},"datePublished":"2021-06-24T18:46:53+00:00","dateModified":"2021-06-24T18:46:54+00:00","breadcrumb":{"@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2021\/06\/24\/coletividade-ideias-que-tomam-forma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/oicriativas.faac.unesp.br\/"},{"@type":"ListItem","position":2,"name":"Coletividade: ideias que tomam forma"}]},{"@type":"WebSite","@id":"https:\/\/oicriativas.faac.unesp.br\/#website","url":"https:\/\/oicriativas.faac.unesp.br\/","name":"Oi Criativas","description":"","publisher":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oicriativas.faac.unesp.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/oicriativas.faac.unesp.br\/#organization","name":"Oi Criativas","url":"https:\/\/oicriativas.faac.unesp.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/","url":"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png","contentUrl":"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png","width":300,"height":118,"caption":"Oi Criativas"},"image":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/8f56b3dc3c300fd061a7ee990c5a43cc","name":"lecotec","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d04c8a97a87b9a1cb7c7db69dacde035?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04c8a97a87b9a1cb7c7db69dacde035?s=96&d=mm&r=g","caption":"lecotec"},"url":"https:\/\/oicriativas.faac.unesp.br\/index.php\/author\/lecotec\/"}]}},"_links":{"self":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts\/1082"}],"collection":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/comments?post=1082"}],"version-history":[{"count":18,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts\/1082\/revisions"}],"predecessor-version":[{"id":1110,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts\/1082\/revisions\/1110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/media\/1084"}],"wp:attachment":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/media?parent=1082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/categories?post=1082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/tags?post=1082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}