{"id":1195,"date":"2023-01-29T22:46:01","date_gmt":"2023-01-30T01:46:01","guid":{"rendered":"https:\/\/oicriativas.faac.unesp.br\/?p=1195"},"modified":"2023-01-29T22:46:03","modified_gmt":"2023-01-30T01:46:03","slug":"startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games","status":"publish","type":"post","link":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/","title":{"rendered":"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games"},"content":{"rendered":"\n<p>Localizada no Rio de Janeiro, a TechZelt \u2013 FazGame \u00e9 uma startup voltada \u00e0 promo\u00e7\u00e3o da educa\u00e7\u00e3o b\u00e1sica em escolas p\u00fablicas em todo o pa\u00eds. Para alcan\u00e7ar esse objetivo, a empresa desenvolveu uma plataforma gamificada, disponibilizada ao professor em sala de aula, que busca facilitar o aprendizado da leitura e escrita, a capacidade de argumentar, o racioc\u00ednio l\u00f3gico e a criatividade. Segundo Carla Zeltzer, fundadora da startup, \u201co prop\u00f3sito da empresa \u00e9 melhorar a educa\u00e7\u00e3o, mexendo no ambiente da sala de aula, tornando a sala de aula mais instigante, mais motivadora e centrada no aluno desenvolvendo atividades\u201d.&nbsp;<\/p>\n\n\n\n<p>A empres\u00e1ria conta que o desafio inicial da ideia do projeto foi criar e padronizar um material pedag\u00f3gico que pudesse ser utilizado por toda e qualquer escola, para toda e qualquer disciplina. \u201cDentro da natureza daquilo que a FazGame oferece, n\u00f3s entendemos que trabalhar a produ\u00e7\u00e3o textual de L\u00edngua Portuguesa seria um ponto oportuno, que conta com espa\u00e7o comercial, al\u00e9m de ser oferecido por poucas solu\u00e7\u00f5es de mercado\u201d, conta Zeltzer.&nbsp;<\/p>\n\n\n\n<p>Para escalar a startup, Carla diz que participar de programas de inova\u00e7\u00e3o e acelera\u00e7\u00e3o de impacto, como os hackathons, \u00e9 fundamental. A fundadora explica que esses eventos e iniciativas colocam donos de startups em contato com outros na mesma posi\u00e7\u00e3o, apoiadores do terceiro setor e outros contatos do mercado.<\/p>\n\n\n\n<p>A empresa tem hoje 22 funcion\u00e1rios e planeja expandir para 26 nos pr\u00f3ximos meses. Os principais clientes s\u00e3o empresas do terceiro setor, escolas particulares ou empresas que buscam promover suas marcas no campo da educa\u00e7\u00e3o.<\/p>\n\n\n\n<p>A TechZelt\u2013FazGame \u00e9 alinhada ao Objetivos de Desenvolvimento Sustent\u00e1vel 4 (Educa\u00e7\u00e3o de Qualidade), 8 (Emprego Digno e Crescimento Econ\u00f4mico) e 10 (Redu\u00e7\u00e3o das Desigualdades).<\/p>\n\n\n\n<p>Quer saber mais sobre a TechZelt\u2013FazGame? <\/p>\n\n\n\n<p>Acesse: <a href=\"https:\/\/anchor.fm\/lecocast\/episodes\/Saberes-da-Inovao-TechZelt-FazGame-e1pnrb2\/a-a8oc96j\">https:\/\/anchor.fm\/lecocast\/episodes\/Saberes-da-Inovao-TechZelt-FazGame-e1pnrb2\/a-a8oc96j<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Localizada no Rio de Janeiro, a TechZelt \u2013 FazGame \u00e9 uma startup voltada \u00e0 promo\u00e7\u00e3o da educa\u00e7\u00e3o b\u00e1sica em escolas p\u00fablicas em todo o pa\u00eds. Para alcan\u00e7ar esse objetivo, a empresa desenvolveu uma plataforma gamificada, disponibilizada ao professor em sala de aula, que busca facilitar o aprendizado da leitura e escrita, a capacidade de argumentar,&hellip;&nbsp;<a href=\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/\" class=\"\" rel=\"bookmark\">Continue a ler &raquo;<span class=\"screen-reader-text\">Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games<\/span><\/a><\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":""},"categories":[180],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games - Oi Criativas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games - Oi Criativas\" \/>\n<meta name=\"twitter:description\" content=\"Localizada no Rio de Janeiro, a TechZelt \u2013 FazGame \u00e9 uma startup voltada \u00e0 promo\u00e7\u00e3o da educa\u00e7\u00e3o b\u00e1sica em escolas p\u00fablicas em todo o pa\u00eds. Para alcan\u00e7ar esse objetivo, a empresa desenvolveu uma plataforma gamificada, disponibilizada ao professor em sala de aula, que busca facilitar o aprendizado da leitura e escrita, a capacidade de argumentar,&hellip;&nbsp;Continue a ler &raquo;Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"V\u00edctor Sim\u00f5es Zamberlan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/\"},\"author\":{\"name\":\"V\u00edctor Sim\u00f5es Zamberlan\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/f7a50739d612928ae0e16bcba27fb8f4\"},\"headline\":\"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games\",\"datePublished\":\"2023-01-30T01:46:01+00:00\",\"dateModified\":\"2023-01-30T01:46:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/\"},\"wordCount\":331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#organization\"},\"articleSection\":[\"Saberes da Inova\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/\",\"name\":\"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games - Oi Criativas\",\"isPartOf\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#website\"},\"datePublished\":\"2023-01-30T01:46:01+00:00\",\"dateModified\":\"2023-01-30T01:46:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/oicriativas.faac.unesp.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#website\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/\",\"name\":\"Oi Criativas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oicriativas.faac.unesp.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#organization\",\"name\":\"Oi Criativas\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png\",\"contentUrl\":\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png\",\"width\":300,\"height\":118,\"caption\":\"Oi Criativas\"},\"image\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/f7a50739d612928ae0e16bcba27fb8f4\",\"name\":\"V\u00edctor Sim\u00f5es Zamberlan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/118f10c1b04702b063e4fb9f7b97eae9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/118f10c1b04702b063e4fb9f7b97eae9?s=96&d=mm&r=g\",\"caption\":\"V\u00edctor Sim\u00f5es Zamberlan\"},\"url\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/author\/victorzamberlan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games - Oi Criativas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/","twitter_card":"summary_large_image","twitter_title":"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games - Oi Criativas","twitter_description":"Localizada no Rio de Janeiro, a TechZelt \u2013 FazGame \u00e9 uma startup voltada \u00e0 promo\u00e7\u00e3o da educa\u00e7\u00e3o b\u00e1sica em escolas p\u00fablicas em todo o pa\u00eds. Para alcan\u00e7ar esse objetivo, a empresa desenvolveu uma plataforma gamificada, disponibilizada ao professor em sala de aula, que busca facilitar o aprendizado da leitura e escrita, a capacidade de argumentar,&hellip;&nbsp;Continue a ler &raquo;Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games","twitter_misc":{"Escrito por":"V\u00edctor Sim\u00f5es Zamberlan","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/#article","isPartOf":{"@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/"},"author":{"name":"V\u00edctor Sim\u00f5es Zamberlan","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/f7a50739d612928ae0e16bcba27fb8f4"},"headline":"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games","datePublished":"2023-01-30T01:46:01+00:00","dateModified":"2023-01-30T01:46:03+00:00","mainEntityOfPage":{"@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/"},"wordCount":331,"commentCount":0,"publisher":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#organization"},"articleSection":["Saberes da Inova\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/","url":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/","name":"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games - Oi Criativas","isPartOf":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#website"},"datePublished":"2023-01-30T01:46:01+00:00","dateModified":"2023-01-30T01:46:03+00:00","breadcrumb":{"@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2023\/01\/29\/startup-promove-educacao-basica-na-rede-publica-do-pais-por-meio-de-games\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/oicriativas.faac.unesp.br\/"},{"@type":"ListItem","position":2,"name":"Startup promove educa\u00e7\u00e3o b\u00e1sica na rede p\u00fablica do pa\u00eds por meio de games"}]},{"@type":"WebSite","@id":"https:\/\/oicriativas.faac.unesp.br\/#website","url":"https:\/\/oicriativas.faac.unesp.br\/","name":"Oi Criativas","description":"","publisher":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oicriativas.faac.unesp.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/oicriativas.faac.unesp.br\/#organization","name":"Oi Criativas","url":"https:\/\/oicriativas.faac.unesp.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/","url":"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png","contentUrl":"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png","width":300,"height":118,"caption":"Oi Criativas"},"image":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/f7a50739d612928ae0e16bcba27fb8f4","name":"V\u00edctor Sim\u00f5es Zamberlan","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/118f10c1b04702b063e4fb9f7b97eae9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/118f10c1b04702b063e4fb9f7b97eae9?s=96&d=mm&r=g","caption":"V\u00edctor Sim\u00f5es Zamberlan"},"url":"https:\/\/oicriativas.faac.unesp.br\/index.php\/author\/victorzamberlan\/"}]}},"_links":{"self":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts\/1195"}],"collection":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/comments?post=1195"}],"version-history":[{"count":1,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts\/1195\/revisions"}],"predecessor-version":[{"id":1196,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts\/1195\/revisions\/1196"}],"wp:attachment":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/media?parent=1195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/categories?post=1195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/tags?post=1195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}