{"id":387,"date":"2014-11-20T15:28:58","date_gmt":"2014-11-20T17:28:58","guid":{"rendered":"http:\/\/oicriativas.faac.unesp.br\/?p=387"},"modified":"2014-11-20T15:28:58","modified_gmt":"2014-11-20T17:28:58","slug":"a-cultura-faz-muito-bem-ao-desenvolvimento","status":"publish","type":"post","link":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/","title":{"rendered":"A cultura faz muito bem ao desenvolvimento"},"content":{"rendered":"<p>No dia 5 de novembro foi comemorado o Dia da Cultura Brasileira. Entendendo que a cultura, enquanto conjunto de valores, tradi\u00e7\u00f5es, patrim\u00f4nio tang\u00edvel e intang\u00edvel, cren\u00e7as, percep\u00e7\u00f5es do mundo e express\u00f5es culturais que moldam como vivemos, pode impulsionar o desenvolvimento, podemos coloc\u00e1-la como a quarta dimens\u00e3o do desenvolvimento sustent\u00e1vel. Afinal, \u00e9 t\u00e3o importante quanto as dimens\u00f5es econ\u00f4mica, social e ambiental, pois torna a defesa do patrim\u00f4nio, da diversidade, da criatividade e da transmiss\u00e3o de conhecimentos um elemento integrante do desenvolvimento sustent\u00e1vel.<\/p>\n<p>No m\u00eas de maio de 2013, foi realizado na cidade de Hangzhou, na China, por iniciativa da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Educa\u00e7\u00e3o, a Ci\u00eancia e a Cultura \u2013 UNESCO, um congresso internacional da maior relev\u00e2ncia para a humanidade e para seu futuro. Sob o tema \u201cA cultura: chave para o desenvolvimento sustent\u00e1vel\u201d, representantes de 81 pa\u00edses e diversas organiza\u00e7\u00f5es internacionais elaboraram a j\u00e1 hist\u00f3rica Declara\u00e7\u00e3o de Hangzhou, exarada daquele evento, um dos mais respeit\u00e1veis documentos deste come\u00e7o de mil\u00eanio a reconhecer e balizar a influ\u00eancia e import\u00e2ncia da cultura para o desenvolvimento sustent\u00e1vel.<\/p>\n<p>Em conson\u00e2ncia com a declara\u00e7\u00e3o de Hangzhou e segundo o Plano da Secretaria da Economia Criativa (2011 a 2014), as transforma\u00e7\u00f5es nas formas de produ\u00e7\u00e3o e consumo nas sociedades modernas t\u00eam no conhecimento e na criatividade sua base dinamizadora.<\/p>\n<p>Por isso, atributos de conhecimento e criatividade constituem fatores de alt\u00edssima relev\u00e2ncia no desenvolvimento social, econ\u00f4mico e pol\u00edtico de um pa\u00eds. O pr\u00f3prio plano de Hangzhou coloca, literalmente: \u201crecomendamos a inclus\u00e3o na agenda das Na\u00e7\u00f5es Unidas para o desenvolvimento p\u00f3s-2015 de um objetivo espec\u00edfico centrado na cultura, baseado no patrim\u00f4nio, na diversidade, na criatividade e na transmiss\u00e3o dos conhecimentos, que inclua metas e indicadores claros ligando a cultura a todas as dimens\u00f5es do desenvolvimento sustent\u00e1vel\u201d.<\/p>\n<p>No Brasil, v\u00e1rias iniciativas destacam a capacidade de estimular o desenvolvimento das atividades produtivas associadas \u00e0s culturais. O desenvolvimento econ\u00f4mico da cultura vai beneficiar o refor\u00e7o das capacidades e o investimento em todos os aspectos de valor das artes, ind\u00fastrias criativas e patrim\u00f4nio cultural tang\u00edvel e intang\u00edvel, criando, consequentemente, postos de trabalho e gerando receitas.<\/p>\n<p>As atividades econ\u00f4micas associadas \u00e0 cultura passam por um processo que vai de sua cria\u00e7\u00e3o, ou conceitualiza\u00e7\u00e3o, investimento, materializa\u00e7\u00e3o ou produ\u00e7\u00e3o, distribui\u00e7\u00e3o, para chegar a sua comercializa\u00e7\u00e3o, gerando valores em todas estas etapas. A dissemina\u00e7\u00e3o da import\u00e2ncia, a valoriza\u00e7\u00e3o e transmiss\u00e3o da cultura\u00a0 na pauta das pol\u00edticas p\u00fablicas de gestores p\u00fablicos, no portf\u00f3lio dos programas apoiados pelas ind\u00fastrias, por meio de Incentivos Fiscais, nas universidades\u00a0 por meio de fomento de cursos de empreeendedorismo social (neg\u00f3cios sociais, verdes, inclusivos e criativos), certamente ir\u00e3o melhorar todas as zonas urbanas e permitir coopera\u00e7\u00e3o inovadora e sustent\u00e1vel. H\u00e1 muita riqueza ainda n\u00e3o aproveitada nos talentos da terra brasilis.<\/p>\n<p><em>Wanda Camargo, educadora das Faculdades Integradas do Brasil &#8211; UniBrasil e Rosane Fontoura, coordenadora executiva do Conselho Paranaense de Cidadania Empresarial &#8211; FIEP.<\/em><\/p>\n<pre>Fonte: <a href=\"http:\/\/www.bemparana.com.br\/noticia\/359044\/a-cultura-faz-muito-bem-ao-desenvolvimento\">Wanda Camargo\/Bem Paran\u00e1<\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>No dia 5 de novembro foi comemorado o Dia da Cultura Brasileira. Entendendo que a cultura, enquanto conjunto de valores, tradi\u00e7\u00f5es, patrim\u00f4nio tang\u00edvel e intang\u00edvel, cren\u00e7as, percep\u00e7\u00f5es do mundo e express\u00f5es culturais que moldam como vivemos, pode impulsionar o desenvolvimento, podemos coloc\u00e1-la como a quarta dimens\u00e3o do desenvolvimento sustent\u00e1vel. Afinal, \u00e9 t\u00e3o importante quanto as&hellip;&nbsp;<a href=\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/\" class=\"\" rel=\"bookmark\">Continue a ler &raquo;<span class=\"screen-reader-text\">A cultura faz muito bem ao desenvolvimento<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":388,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":""},"categories":[9],"tags":[29,70,69],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A cultura faz muito bem ao desenvolvimento - Oi Criativas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"A cultura faz muito bem ao desenvolvimento - Oi Criativas\" \/>\n<meta name=\"twitter:description\" content=\"No dia 5 de novembro foi comemorado o Dia da Cultura Brasileira. Entendendo que a cultura, enquanto conjunto de valores, tradi\u00e7\u00f5es, patrim\u00f4nio tang\u00edvel e intang\u00edvel, cren\u00e7as, percep\u00e7\u00f5es do mundo e express\u00f5es culturais que moldam como vivemos, pode impulsionar o desenvolvimento, podemos coloc\u00e1-la como a quarta dimens\u00e3o do desenvolvimento sustent\u00e1vel. Afinal, \u00e9 t\u00e3o importante quanto as&hellip;&nbsp;Continue a ler &raquo;A cultura faz muito bem ao desenvolvimento\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2014\/11\/cultura.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lecotec\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/\"},\"author\":{\"name\":\"lecotec\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/8f56b3dc3c300fd061a7ee990c5a43cc\"},\"headline\":\"A cultura faz muito bem ao desenvolvimento\",\"datePublished\":\"2014-11-20T17:28:58+00:00\",\"dateModified\":\"2014-11-20T17:28:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/\"},\"wordCount\":551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#organization\"},\"keywords\":[\"Economia Criativa\",\"Internacional\",\"ONU\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/\",\"name\":\"A cultura faz muito bem ao desenvolvimento - Oi Criativas\",\"isPartOf\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#website\"},\"datePublished\":\"2014-11-20T17:28:58+00:00\",\"dateModified\":\"2014-11-20T17:28:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/oicriativas.faac.unesp.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A cultura faz muito bem ao desenvolvimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#website\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/\",\"name\":\"Oi Criativas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oicriativas.faac.unesp.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#organization\",\"name\":\"Oi Criativas\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png\",\"contentUrl\":\"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png\",\"width\":300,\"height\":118,\"caption\":\"Oi Criativas\"},\"image\":{\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/8f56b3dc3c300fd061a7ee990c5a43cc\",\"name\":\"lecotec\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d04c8a97a87b9a1cb7c7db69dacde035?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d04c8a97a87b9a1cb7c7db69dacde035?s=96&d=mm&r=g\",\"caption\":\"lecotec\"},\"url\":\"https:\/\/oicriativas.faac.unesp.br\/index.php\/author\/lecotec\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A cultura faz muito bem ao desenvolvimento - Oi Criativas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/","twitter_card":"summary_large_image","twitter_title":"A cultura faz muito bem ao desenvolvimento - Oi Criativas","twitter_description":"No dia 5 de novembro foi comemorado o Dia da Cultura Brasileira. Entendendo que a cultura, enquanto conjunto de valores, tradi\u00e7\u00f5es, patrim\u00f4nio tang\u00edvel e intang\u00edvel, cren\u00e7as, percep\u00e7\u00f5es do mundo e express\u00f5es culturais que moldam como vivemos, pode impulsionar o desenvolvimento, podemos coloc\u00e1-la como a quarta dimens\u00e3o do desenvolvimento sustent\u00e1vel. Afinal, \u00e9 t\u00e3o importante quanto as&hellip;&nbsp;Continue a ler &raquo;A cultura faz muito bem ao desenvolvimento","twitter_image":"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2014\/11\/cultura.jpg","twitter_misc":{"Escrito por":"lecotec","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/#article","isPartOf":{"@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/"},"author":{"name":"lecotec","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/8f56b3dc3c300fd061a7ee990c5a43cc"},"headline":"A cultura faz muito bem ao desenvolvimento","datePublished":"2014-11-20T17:28:58+00:00","dateModified":"2014-11-20T17:28:58+00:00","mainEntityOfPage":{"@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/"},"wordCount":551,"commentCount":0,"publisher":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#organization"},"keywords":["Economia Criativa","Internacional","ONU"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/","url":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/","name":"A cultura faz muito bem ao desenvolvimento - Oi Criativas","isPartOf":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#website"},"datePublished":"2014-11-20T17:28:58+00:00","dateModified":"2014-11-20T17:28:58+00:00","breadcrumb":{"@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oicriativas.faac.unesp.br\/index.php\/2014\/11\/20\/a-cultura-faz-muito-bem-ao-desenvolvimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/oicriativas.faac.unesp.br\/"},{"@type":"ListItem","position":2,"name":"A cultura faz muito bem ao desenvolvimento"}]},{"@type":"WebSite","@id":"https:\/\/oicriativas.faac.unesp.br\/#website","url":"https:\/\/oicriativas.faac.unesp.br\/","name":"Oi Criativas","description":"","publisher":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oicriativas.faac.unesp.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/oicriativas.faac.unesp.br\/#organization","name":"Oi Criativas","url":"https:\/\/oicriativas.faac.unesp.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/","url":"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png","contentUrl":"https:\/\/oicriativas.faac.unesp.br\/wp-content\/uploads\/2021\/04\/cropped-Transparente-300-px.png","width":300,"height":118,"caption":"Oi Criativas"},"image":{"@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/8f56b3dc3c300fd061a7ee990c5a43cc","name":"lecotec","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oicriativas.faac.unesp.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d04c8a97a87b9a1cb7c7db69dacde035?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04c8a97a87b9a1cb7c7db69dacde035?s=96&d=mm&r=g","caption":"lecotec"},"url":"https:\/\/oicriativas.faac.unesp.br\/index.php\/author\/lecotec\/"}]}},"_links":{"self":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts\/387"}],"collection":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/comments?post=387"}],"version-history":[{"count":1,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts\/387\/revisions"}],"predecessor-version":[{"id":389,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/posts\/387\/revisions\/389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/media\/388"}],"wp:attachment":[{"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/media?parent=387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/categories?post=387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oicriativas.faac.unesp.br\/index.php\/wp-json\/wp\/v2\/tags?post=387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}